{"id":16243,"date":"2024-04-29T20:24:26","date_gmt":"2024-04-29T18:24:26","guid":{"rendered":"https:\/\/www.interpeace.org\/?p=16243"},"modified":"2024-04-30T17:44:47","modified_gmt":"2024-04-30T15:44:47","slug":"the-launch-of-rwandas-first-resilience-assessment-framework","status":"publish","type":"post","link":"https:\/\/www.interpeace.org\/fr\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/","title":{"rendered":"Le lancement du premier cadre d\u2019\u00e9valuation de la r\u00e9silience du Rwanda"},"content":{"rendered":"<p>Le minist\u00e8re de l'Unit\u00e9 nationale et de l'engagement civique (MINUBUMWE), en collaboration avec Interpeace, a publi\u00e9 une nouvelle recherche intitul\u00e9e : \u00ab Un cadre participatif communautaire pour l'\u00e9valuation de la r\u00e9silience au Rwanda \u00bb. Ces r\u00e9sultats ont \u00e9t\u00e9 pr\u00e9sent\u00e9s, accompagn\u00e9s de recommandations judicieuses, lors d'un \u00e9v\u00e9nement de mobilisation des parties prenantes qui s'est tenu le 8 mars 2024 \u00e0 Kigali.<\/p>\r\n\r\n\r\n\r\n<p>L\u2019objectif de cette \u00e9tude, men\u00e9e dans les 30 districts du Rwanda, \u00e9tait quadruple. Premi\u00e8rement, celle-ci visait \u00e0 formuler et \u00e0 valider des indicateurs de r\u00e9silience pour structurer les futures activit\u00e9s de recherche, politiques et programmes li\u00e9s \u00e0 la r\u00e9silience communautaire au Rwanda. Deuxi\u00e8mement, elle cherchait \u00e0 concevoir une m\u00e9thodologie participative \u00e0 plusieurs niveaux pour \u00e9valuer les indicateurs de r\u00e9silience, en s'appuyant sur les cadres existants, tout en les adaptant au contexte sp\u00e9cifique du Rwanda. En outre, l'\u00e9tude visait \u00e0 \u00e9tablir une base de r\u00e9f\u00e9rence pour la r\u00e9silience communautaire dans tous les districts du Rwanda et \u00e0 proposer des recommandations politiques et programmatiques concr\u00e8tes pour renforcer celle \u00e0 l'\u00e9chelle nationale. Impliquant un \u00e9chantillon significatif de 7 481 personnes, elle a adopt\u00e9 une approche \u00e0 m\u00e9thodes mixtes, int\u00e9grant \u00e0 la fois des m\u00e9thodes qualitatives et quantitatives. La r\u00e9silience a \u00e9t\u00e9 \u00e9valu\u00e9e \u00e0 quatre niveaux : individuel, familial, communautaire et institutionnel, \u00e0 l'aide d'un ensemble complet de 38 indicateurs.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16244 size-medium\" src=\"https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study2-533x400.jpeg\" alt=\"\" width=\"533\" height=\"400\" srcset=\"https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study2-533x400.jpeg 533w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study2-667x500.jpeg 667w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study2-267x200.jpeg 267w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study2-768x576.jpeg 768w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study2-1536x1152.jpeg 1536w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study2-2048x1536.jpeg 2048w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study2-16x12.jpeg 16w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study2-500x375.jpeg 500w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study2-scaled.jpeg 2560w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/><\/figure>\r\n\r\n\r\n\r\n<p>Les r\u00e9sultats ont soulign\u00e9 un degr\u00e9 louable de r\u00e9silience \u00e0 tous les niveaux \u00e9valu\u00e9s, montrant une \u00e9tape importante trois d\u00e9cennies apr\u00e8s le g\u00e9nocide contre les Tutsis. Les recommandations ont soulign\u00e9 la n\u00e9cessit\u00e9 d'intensifier les efforts en mati\u00e8re d'initiatives de gu\u00e9rison soci\u00e9tale, de d\u00e9veloppement des infrastructures et de facilitation de l'acc\u00e8s au financement et aux opportunit\u00e9s d'emploi.<\/p>\r\n\r\n\r\n\r\n<p>Lors de l'\u00e9v\u00e9nement de mobilisation des parties prenantes, le professeur Fran\u00e7ois Masabo, ma\u00eetre de conf\u00e9rences et chercheur \u00e0 l'Universit\u00e9 du Rwanda, a salu\u00e9 l'\u00e9tude. Il a reconnu son approche holistique et son alignement sur les r\u00e9alit\u00e9s contextuelles du Rwanda.<\/p>\r\n\r\n\r\n\r\n<p>L'\u00e9tude a re\u00e7u le soutien financier du gouvernement su\u00e9dois par l'interm\u00e9diaire de son ambassade au Rwanda. Martina Fors Mohlin, conseill\u00e8re et cheffe de la coop\u00e9ration au d\u00e9veloppement de cette ambassade, a r\u00e9it\u00e9r\u00e9 l'engagement de la Su\u00e8de \u00e0 soutenir la mise en \u0153uvre du cadre d\u00e9velopp\u00e9 au sein des communaut\u00e9s rwandaises. \u00ab Nous sommes fiers d'avoir particip\u00e9 \u00e0 cette \u00e9tude en soutenant Interpeace ainsi que le minist\u00e8re (MINUBUMWE) et en permettant \u00e0 cette conversation d'avoir lieu. J'ai vraiment h\u00e2te de travailler ensemble pour faire avancer ces conclusions \u00e0 mesure que nous les mettons en \u0153uvre dans la soci\u00e9t\u00e9 \u00bb, a-t-elle not\u00e9.<\/p>\r\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-16243 gallery-columns-2 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.interpeace.org\/fr\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/rwanda-resilience-study7\/'><img loading=\"lazy\" decoding=\"async\" width=\"267\" height=\"200\" src=\"https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study7-267x200.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study7-267x200.jpeg 267w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study7-533x400.jpeg 533w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study7-667x500.jpeg 667w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study7-768x576.jpeg 768w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study7-1536x1152.jpeg 1536w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study7-2048x1536.jpeg 2048w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study7-16x12.jpeg 16w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study7-500x375.jpeg 500w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study7-scaled.jpeg 2560w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.interpeace.org\/fr\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/rwanda-resilience-study3\/'><img loading=\"lazy\" decoding=\"async\" width=\"267\" height=\"200\" src=\"https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study3-267x200.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study3-267x200.jpeg 267w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study3-533x400.jpeg 533w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study3-667x500.jpeg 667w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study3-768x576.jpeg 768w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study3-1536x1152.jpeg 1536w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study3-2048x1536.jpeg 2048w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study3-16x12.jpeg 16w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study3-500x375.jpeg 500w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study3-scaled.jpeg 2560w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\r\n\r\n\r\n\r\n<p>Le Cadre participatif communautaire pour l\u2019\u00e9valuation de la r\u00e9silience constitue une initiative historique au Rwanda. Il sert de point de r\u00e9f\u00e9rence fondamental pour les futures \u00e9tudes dans le domaine de la r\u00e9silience au sein du pays. Le ministre de l'unit\u00e9 nationale et de l'engagement civique, Jean Damascene Bizimana, a soulign\u00e9 l'opportunit\u00e9 de la recherche, notant le changement du Gouvernement du Rwanda \u00e0 travers la MINUBUMWE, vers l'am\u00e9lioration et le renforcement de la r\u00e9silience des Rwandais face aux d\u00e9fis persistants d\u00e9coulant des cons\u00e9quences du g\u00e9nocide contre les Tutsis.<\/p>\r\n\r\n\r\n\r\n<p>\u00ab La r\u00e9silience est l\u2019une des valeurs rwandaises. Nous voulons concevoir des programmes et des initiatives qui s\u2019inspirent de nos valeurs culturelles et qui contribueront \u00e0 r\u00e9soudre efficacement nos probl\u00e8mes sp\u00e9cifiques. Cette recherche que le MINUBUMWE a men\u00e9e conjointement avec Interpeace r\u00e9pond \u00e0 ce besoin. Cela nous permettra de renforcer la r\u00e9silience des Rwandais, de construire un pays apais\u00e9 et prosp\u00e8re bas\u00e9 sur des indicateurs concrets et r\u00e9alistes \u00bb, a d\u00e9clar\u00e9 Jean Damascene Bizimana.<\/p>\r\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-2 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-2 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-2' class='gallery galleryid-16243 gallery-columns-2 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.interpeace.org\/fr\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/rwanda-resilience-study4\/'><img loading=\"lazy\" decoding=\"async\" width=\"267\" height=\"200\" src=\"https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study4-267x200.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study4-267x200.jpeg 267w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study4-533x400.jpeg 533w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study4-667x500.jpeg 667w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study4-768x576.jpeg 768w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study4-1536x1152.jpeg 1536w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study4-2048x1536.jpeg 2048w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study4-16x12.jpeg 16w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study4-500x375.jpeg 500w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study4-scaled.jpeg 2560w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.interpeace.org\/fr\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/rwanda-resilience-study1\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study1-300x200.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study1-300x200.jpeg 300w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study1-600x400.jpeg 600w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study1-750x500.jpeg 750w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study1-768x512.jpeg 768w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study1-1536x1024.jpeg 1536w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study1-2048x1365.jpeg 2048w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study1-18x12.jpeg 18w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study1-500x333.jpeg 500w, https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study1-scaled.jpeg 2560w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\r\n\r\n\r\n\r\n<p>Pour aller de l\u2019avant, une feuille de route compl\u00e8te est actuellement en cours de lancement. Elle guidera la mise en \u0153uvre des conclusions et des recommandations d\u00e9riv\u00e9es de l\u2019\u00e9tude de recherche. Elle \u0153uvre comme plan strat\u00e9gique pour toutes les parties prenantes impliqu\u00e9es dans les efforts de gu\u00e9rison et de r\u00e9silience soci\u00e9tale. Chaque partie prenante sera charg\u00e9e d\u2019\u00e9tablir des objectifs strat\u00e9giques et programmatiques sp\u00e9cifiques, ainsi que les cibles et actions correspondantes. Ceux-ci visent \u00e0 p\u00e9renniser les gains r\u00e9alis\u00e9s en mati\u00e8re de r\u00e9silience tout en s\u2019attaquant simultan\u00e9ment aux \u00e9ventuelles fragilit\u00e9s identifi\u00e9es au cours de l\u2019\u00e9tude de recherche. \u00a0\u00a0<\/p>\r\n<p><iframe loading=\"lazy\" title=\"National Stakeholders Engagement\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/-7hBISv2AGI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>The Ministry of National Unity and Civic Engagement (MINUBUMWE), in collaboration with Interpeace has released new research titled: a Community-based Participatory Framework for the Assessment of Resilience in Rwanda. These findings were presented, along with insightful recommendations, during a stakeholder engagement event held on 8 March 2024 in Kigali, Rwanda. The objective of this study, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16270,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","editor_plus_copied_stylings":"{}","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"globales":[],"initiatives":[],"news_type":[],"programmes":[74],"resource_theme":[514],"videos_vimeo":[],"class_list":["post-16243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","programmes-rwanda","resource_theme-civil-society"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>The launch of Rwanda\u2019s first Resilience Assessment Framework - Interpeace<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.interpeace.org\/fr\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The launch of Rwanda\u2019s first Resilience Assessment Framework\" \/>\n<meta property=\"og:description\" content=\"The Ministry of National Unity and Civic Engagement (MINUBUMWE), in collaboration with Interpeace has released new research titled: a Community-based Participatory Framework for the Assessment of Resilience in Rwanda. These findings were presented, along with insightful recommendations, during a stakeholder engagement event held on 8 March 2024 in Kigali, Rwanda. The objective of this study, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.interpeace.org\/fr\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/\" \/>\n<meta property=\"og:site_name\" content=\"Interpeace\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Interpeace\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-29T18:24:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-30T15:44:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study8-1-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alejandro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@InterpeaceTweet\" \/>\n<meta name=\"twitter:site\" content=\"@InterpeaceTweet\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alejandro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/2024\\\/04\\\/the-launch-of-rwandas-first-resilience-assessment-framework\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/2024\\\/04\\\/the-launch-of-rwandas-first-resilience-assessment-framework\\\/\"},\"author\":{\"name\":\"Alejandro\",\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/#\\\/schema\\\/person\\\/75fea8ede2ce310d5f1bea81166bf9a1\"},\"headline\":\"The launch of Rwanda\u2019s first Resilience Assessment Framework\",\"datePublished\":\"2024-04-29T18:24:26+00:00\",\"dateModified\":\"2024-04-30T15:44:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/2024\\\/04\\\/the-launch-of-rwandas-first-resilience-assessment-framework\\\/\"},\"wordCount\":589,\"publisher\":{\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/2024\\\/04\\\/the-launch-of-rwandas-first-resilience-assessment-framework\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.interpeace.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Rwanda-Resilience-study8-1-scaled.jpeg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/2024\\\/04\\\/the-launch-of-rwandas-first-resilience-assessment-framework\\\/\",\"url\":\"https:\\\/\\\/www.interpeace.org\\\/2024\\\/04\\\/the-launch-of-rwandas-first-resilience-assessment-framework\\\/\",\"name\":\"The launch of Rwanda\u2019s first Resilience Assessment Framework - Interpeace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/2024\\\/04\\\/the-launch-of-rwandas-first-resilience-assessment-framework\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/2024\\\/04\\\/the-launch-of-rwandas-first-resilience-assessment-framework\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.interpeace.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Rwanda-Resilience-study8-1-scaled.jpeg\",\"datePublished\":\"2024-04-29T18:24:26+00:00\",\"dateModified\":\"2024-04-30T15:44:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/2024\\\/04\\\/the-launch-of-rwandas-first-resilience-assessment-framework\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.interpeace.org\\\/2024\\\/04\\\/the-launch-of-rwandas-first-resilience-assessment-framework\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/2024\\\/04\\\/the-launch-of-rwandas-first-resilience-assessment-framework\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.interpeace.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Rwanda-Resilience-study8-1-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.interpeace.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Rwanda-Resilience-study8-1-scaled.jpeg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/2024\\\/04\\\/the-launch-of-rwandas-first-resilience-assessment-framework\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.interpeace.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The launch of Rwanda\u2019s first Resilience Assessment Framework\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/#website\",\"url\":\"https:\\\/\\\/www.interpeace.org\\\/\",\"name\":\"Interpeace\",\"description\":\"Enabling people to build lasting peace since 1994\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.interpeace.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/#organization\",\"name\":\"INTERPEACE\",\"url\":\"https:\\\/\\\/www.interpeace.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.interpeace.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/EN-Interpeace-small.png\",\"contentUrl\":\"https:\\\/\\\/www.interpeace.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/EN-Interpeace-small.png\",\"width\":111,\"height\":85,\"caption\":\"INTERPEACE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Interpeace\",\"https:\\\/\\\/x.com\\\/InterpeaceTweet\",\"https:\\\/\\\/www.instagram.com\\\/interpeace\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.interpeace.org\\\/#\\\/schema\\\/person\\\/75fea8ede2ce310d5f1bea81166bf9a1\",\"name\":\"Alejandro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5627fb156910981ea3ab2405e881b80c8234e50bb58a577081f805dd3bfd753?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5627fb156910981ea3ab2405e881b80c8234e50bb58a577081f805dd3bfd753?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5627fb156910981ea3ab2405e881b80c8234e50bb58a577081f805dd3bfd753?s=96&d=mm&r=g\",\"caption\":\"Alejandro\"},\"url\":\"https:\\\/\\\/www.interpeace.org\\\/fr\\\/author\\\/amoralesruiz-gm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"The launch of Rwanda\u2019s first Resilience Assessment Framework - Interpeace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.interpeace.org\/fr\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/","og_locale":"fr_FR","og_type":"article","og_title":"The launch of Rwanda\u2019s first Resilience Assessment Framework","og_description":"The Ministry of National Unity and Civic Engagement (MINUBUMWE), in collaboration with Interpeace has released new research titled: a Community-based Participatory Framework for the Assessment of Resilience in Rwanda. These findings were presented, along with insightful recommendations, during a stakeholder engagement event held on 8 March 2024 in Kigali, Rwanda. The objective of this study, [&hellip;]","og_url":"https:\/\/www.interpeace.org\/fr\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/","og_site_name":"Interpeace","article_publisher":"https:\/\/www.facebook.com\/Interpeace","article_published_time":"2024-04-29T18:24:26+00:00","article_modified_time":"2024-04-30T15:44:47+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study8-1-scaled.jpeg","type":"image\/jpeg"}],"author":"Alejandro","twitter_card":"summary_large_image","twitter_creator":"@InterpeaceTweet","twitter_site":"@InterpeaceTweet","twitter_misc":{"\u00c9crit par":"Alejandro","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.interpeace.org\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/#article","isPartOf":{"@id":"https:\/\/www.interpeace.org\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/"},"author":{"name":"Alejandro","@id":"https:\/\/www.interpeace.org\/#\/schema\/person\/75fea8ede2ce310d5f1bea81166bf9a1"},"headline":"The launch of Rwanda\u2019s first Resilience Assessment Framework","datePublished":"2024-04-29T18:24:26+00:00","dateModified":"2024-04-30T15:44:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.interpeace.org\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/"},"wordCount":589,"publisher":{"@id":"https:\/\/www.interpeace.org\/#organization"},"image":{"@id":"https:\/\/www.interpeace.org\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/#primaryimage"},"thumbnailUrl":"https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study8-1-scaled.jpeg","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.interpeace.org\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/","url":"https:\/\/www.interpeace.org\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/","name":"The launch of Rwanda\u2019s first Resilience Assessment Framework - Interpeace","isPartOf":{"@id":"https:\/\/www.interpeace.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.interpeace.org\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/#primaryimage"},"image":{"@id":"https:\/\/www.interpeace.org\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/#primaryimage"},"thumbnailUrl":"https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study8-1-scaled.jpeg","datePublished":"2024-04-29T18:24:26+00:00","dateModified":"2024-04-30T15:44:47+00:00","breadcrumb":{"@id":"https:\/\/www.interpeace.org\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.interpeace.org\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.interpeace.org\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/#primaryimage","url":"https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study8-1-scaled.jpeg","contentUrl":"https:\/\/www.interpeace.org\/wp-content\/uploads\/2024\/04\/Rwanda-Resilience-study8-1-scaled.jpeg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.interpeace.org\/2024\/04\/the-launch-of-rwandas-first-resilience-assessment-framework\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.interpeace.org\/"},{"@type":"ListItem","position":2,"name":"The launch of Rwanda\u2019s first Resilience Assessment Framework"}]},{"@type":"WebSite","@id":"https:\/\/www.interpeace.org\/#website","url":"https:\/\/www.interpeace.org\/","name":"Interpeace","description":"Permettre aux gens de construire une paix durable depuis 1994","publisher":{"@id":"https:\/\/www.interpeace.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.interpeace.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.interpeace.org\/#organization","name":"INTERPEACE","url":"https:\/\/www.interpeace.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.interpeace.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.interpeace.org\/wp-content\/uploads\/2019\/11\/EN-Interpeace-small.png","contentUrl":"https:\/\/www.interpeace.org\/wp-content\/uploads\/2019\/11\/EN-Interpeace-small.png","width":111,"height":85,"caption":"INTERPEACE"},"image":{"@id":"https:\/\/www.interpeace.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Interpeace","https:\/\/x.com\/InterpeaceTweet","https:\/\/www.instagram.com\/interpeace\/"]},{"@type":"Person","@id":"https:\/\/www.interpeace.org\/#\/schema\/person\/75fea8ede2ce310d5f1bea81166bf9a1","name":"Alejandro","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a5627fb156910981ea3ab2405e881b80c8234e50bb58a577081f805dd3bfd753?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a5627fb156910981ea3ab2405e881b80c8234e50bb58a577081f805dd3bfd753?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a5627fb156910981ea3ab2405e881b80c8234e50bb58a577081f805dd3bfd753?s=96&d=mm&r=g","caption":"Alejandro"},"url":"https:\/\/www.interpeace.org\/fr\/author\/amoralesruiz-gm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.interpeace.org\/fr\/wp-json\/wp\/v2\/posts\/16243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.interpeace.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.interpeace.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.interpeace.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.interpeace.org\/fr\/wp-json\/wp\/v2\/comments?post=16243"}],"version-history":[{"count":0,"href":"https:\/\/www.interpeace.org\/fr\/wp-json\/wp\/v2\/posts\/16243\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.interpeace.org\/fr\/wp-json\/wp\/v2\/media\/16270"}],"wp:attachment":[{"href":"https:\/\/www.interpeace.org\/fr\/wp-json\/wp\/v2\/media?parent=16243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.interpeace.org\/fr\/wp-json\/wp\/v2\/categories?post=16243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.interpeace.org\/fr\/wp-json\/wp\/v2\/tags?post=16243"},{"taxonomy":"globales","embeddable":true,"href":"https:\/\/www.interpeace.org\/fr\/wp-json\/wp\/v2\/globales?post=16243"},{"taxonomy":"initiatives","embeddable":true,"href":"https:\/\/www.interpeace.org\/fr\/wp-json\/wp\/v2\/initiatives?post=16243"},{"taxonomy":"news_type","embeddable":true,"href":"https:\/\/www.interpeace.org\/fr\/wp-json\/wp\/v2\/news_type?post=16243"},{"taxonomy":"programmes","embeddable":true,"href":"https:\/\/www.interpeace.org\/fr\/wp-json\/wp\/v2\/programmes?post=16243"},{"taxonomy":"resource_theme","embeddable":true,"href":"https:\/\/www.interpeace.org\/fr\/wp-json\/wp\/v2\/resource_theme?post=16243"},{"taxonomy":"videos_vimeo","embeddable":true,"href":"https:\/\/www.interpeace.org\/fr\/wp-json\/wp\/v2\/videos_vimeo?post=16243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}